{"id":120,"date":"2015-05-04T07:30:41","date_gmt":"2015-05-04T07:30:41","guid":{"rendered":"https:\/\/xml-io.proteusthemes.com\/cargopress\/?page_id=120"},"modified":"2025-02-07T09:56:10","modified_gmt":"2025-02-07T08:56:10","slug":"contactez-nous","status":"publish","type":"page","link":"https:\/\/bachirtours.com\/tours\/contactez-nous\/","title":{"rendered":"Contactez nous"},"content":{"rendered":"<div id=\"pl-120\"  class=\"panel-layout\" ><div id=\"pg-120-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-120-0\" data-stretch-type=\"full-width-stretch\" ><div id=\"pgc-120-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-120-0-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-a258e6bfa2d8-120\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img decoding=\"async\" src=\"https:\/\/bachirtours.com\/tours\/wp-content\/uploads\/2020\/04\/Contact_us.jpg\" width=\"2401\" height=\"600\" srcset=\"https:\/\/bachirtours.com\/tours\/wp-content\/uploads\/2020\/04\/Contact_us.jpg 2401w, https:\/\/bachirtours.com\/tours\/wp-content\/uploads\/2020\/04\/Contact_us-300x75.jpg 300w, https:\/\/bachirtours.com\/tours\/wp-content\/uploads\/2020\/04\/Contact_us-768x192.jpg 768w, https:\/\/bachirtours.com\/tours\/wp-content\/uploads\/2020\/04\/Contact_us-1024x256.jpg 1024w\" sizes=\"(max-width: 2401px) 100vw, 2401px\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-120-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-120-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-120-1-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child\" data-index=\"1\" ><div class=\"featured-widget panel-widget-style panel-widget-style-for-120-1-0-0\" ><h3 class=\"widget-title\"><span class=\"widget-title__inline\">INFO DE CONTACT<\/span><\/h3><div class=\"textwidget\"><p><strong>BACHIR &amp; Fr\u00e8res Tours<\/strong><\/p>\n<p>DR OLD KHLIFA AIN CHKEF<\/p>\n<p>FES-MAROC<\/p>\n<p>+212 6 61-25-79-00<\/p>\n<p>+212 6 62-07-00-35<\/p>\n<p><a href=\"bachirtours@gmail.com\">bachirtours@gmail.com<\/a><\/p>\n<\/div><\/div><\/div><div id=\"panel-120-1-0-1\" class=\"so-panel widget widget_pw_icon_box widget-icon-box panel-last-child\" data-index=\"2\" >\n\n\t\t<div class=\"icon-box\">\n\n\t\t<i class=\"fa  fa-clock-o\"><\/i>\n\t\t<h4 class=\"icon-box__title\">Horaire d\u2019ouverture<\/h4>\n\t\t<span class=\"icon-box__subtitle\">24H\/24 - 7 Jours\/7<\/span>\n\n\t\t<\/div>\n\n<\/div><\/div><div id=\"pgc-120-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-120-1-1-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"3\" ><h3 class=\"widget-title\"><span class=\"widget-title__inline\">Envoyer nous un E-mail<\/span><\/h3><div class=\"textwidget\"><blockquote><p>Veuillez nous contacter pour toute information ou demande de devis. nous sommes \u00e0 votre disposition, et nous allons vous r\u00e9pondre dans les 24 heures qui suivent.<\/p><\/blockquote>\n<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f122-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"122\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tours\/wp-json\/wp\/v2\/pages\/120#wpcf7-f122-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"122\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f122-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-xs-12  col-md-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12  col-md-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Last Name\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-xs-12  col-md-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail address\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12  col-md-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone Number\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-xs-12  col-md-8\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Subject\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-primary\" type=\"submit\" value=\"SEND MESSAGE\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><label class=\"apbct_special_field\" id=\"apbct_label_id51738\" for=\"apbct__email_id__wp_contact_form_7_51738\">51738<\/label><input\n            id=\"apbct__email_id__wp_contact_form_7_51738\"\n            class=\"apbct_special_field apbct__email_id__wp_contact_form_7\"\n            name=\"apbct__email_id__wp_contact_form_7_51738\"\n            type=\"text\" size=\"30\" maxlength=\"200\" autocomplete=\"off\"\n            value=\"51738\" apbct_event_id=\"51738\"\n            \/><input id=\"apbct_event_id_wp_contact_form_7_51738\"\n                class=\"apbct_special_field\" name=\"apbct_event_id\" type=\"hidden\" value=\"51738\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>BACHIR &amp; Fr\u00e8res Tours DR OLD KHLIFA AIN CHKEF FES-MAROC +212 6 61-25-79-00 +212 6 62-07-00-35 bachirtours@gmail.com Veuillez nous contacter pour toute information ou demande de devis. nous sommes \u00e0 votre disposition, et nous allons vous r\u00e9pondre dans les 24 heures qui suivent.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-120","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bachirtours.com\/tours\/wp-json\/wp\/v2\/pages\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bachirtours.com\/tours\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bachirtours.com\/tours\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bachirtours.com\/tours\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bachirtours.com\/tours\/wp-json\/wp\/v2\/comments?post=120"}],"version-history":[{"count":14,"href":"https:\/\/bachirtours.com\/tours\/wp-json\/wp\/v2\/pages\/120\/revisions"}],"predecessor-version":[{"id":1176,"href":"https:\/\/bachirtours.com\/tours\/wp-json\/wp\/v2\/pages\/120\/revisions\/1176"}],"wp:attachment":[{"href":"https:\/\/bachirtours.com\/tours\/wp-json\/wp\/v2\/media?parent=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}